{"id":3404,"date":"2021-11-23T11:26:52","date_gmt":"2021-11-23T10:26:52","guid":{"rendered":"https:\/\/www.diocesidiroma.it\/catechistico\/?p=3404"},"modified":"2023-03-29T10:03:22","modified_gmt":"2023-03-29T08:03:22","slug":"momento-della-luce-tempo-di-avvento-e-natale","status":"publish","type":"post","link":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/momento-della-luce-tempo-di-avvento-e-natale\/","title":{"rendered":"Momento della Luce &#8211; Tempo di Avvento e Natale 2021"},"content":{"rendered":"<p>Carissimi,<\/p>\n<p>in allegato trovate la proposta del Momento della Luce per il periodo di Avvento e Natale.<\/p>\n<p>Vi indichiamo due tracce alternative per i testi e le domande, quella di quest&#8217;anno sui personaggi evangelici (&#8220;A&#8221;) e quella dell&#8217;anno scorso sul presepe (&#8220;B&#8221;). Proponete alle famiglie quella che ritenete pi\u00f9 adatta.<\/p>\n<p>Questi incontri di condivisione familiare sono, a nostro parere, un elemento centrale nel percorso di iniziazione cristiana e costituiscono una possibilit\u00e0 accessibile a tutte le famiglie, anche quelle meno praticanti.<\/p>\n<p>In allegato trovate anche un modello di lettera ai genitori e lo schema generale del momento della luce. Nella lettera c&#8217;\u00e8 il link al video tutorial di 8 minuti.<\/p>\n<p>Buon Avvento!<\/p>\n<!-- WP Attachments -->\r\n        <div style=\"width:100%;margin:10px 0 10px 0;\">\r\n            <h3>Allegati<\/h3>\r\n        <ul class=\"post-attachments\"><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.diocesidiroma.it\/catechistico\/wp-content\/uploads\/2021\/11\/Momento-della-Luce-2021-Modello-Lettera-genitori-Avvento.pdf\">Momento della Luce 2021 Modello Lettera genitori Avvento<\/a> <small>(34 kB)<\/small><\/li><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.diocesidiroma.it\/catechistico\/wp-content\/uploads\/2021\/11\/Momento-della-Luce-2021-schema.pdf\">Momento della Luce 2021 schema<\/a> <small>(59 kB)<\/small><\/li><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.diocesidiroma.it\/catechistico\/wp-content\/uploads\/2021\/11\/Momento-della-Luce-2021-Avvento-testi-e-domande-traccia-A.pdf\">Momento della Luce 2021 Avvento testi e domande traccia A<\/a> <small>(70 kB)<\/small><\/li><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.diocesidiroma.it\/catechistico\/wp-content\/uploads\/2021\/11\/Momento-della-Luce-2021-Avvento-testi-e-domande-traccia-B.pdf\">Momento della Luce 2021 Avvento testi e domande traccia B<\/a> <small>(60 kB)<\/small><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"Carissimi, in allegato trovate la proposta del Momento della Luce per il periodo di Avvento e Natale. Vi indichiamo due tracce alternative per i testi e le domande, quella di quest&#8217;anno sui personaggi evangelici (&#8220;A&#8221;) e quella dell&#8217;anno scorso sul presepe (&#8220;B&#8221;). Proponete alle famiglie quella che ritenete pi\u00f9 adatta. Questi incontri di condivisione familiare [&hellip;]","protected":false},"author":2,"featured_media":3471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29,32,13,17,49,4],"tags":[],"class_list":["post-3404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunione","category-formazione-catechisti","category-in_evidenza","category-iniziazione-cristiana","category-momento-della-luce","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/comments?post=3404"}],"version-history":[{"count":3,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3404\/revisions"}],"predecessor-version":[{"id":3427,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3404\/revisions\/3427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/media\/3471"}],"wp:attachment":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/media?parent=3404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/categories?post=3404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/tags?post=3404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}