{"id":3464,"date":"2022-01-07T06:00:52","date_gmt":"2022-01-07T05:00:52","guid":{"rendered":"https:\/\/www.diocesidiroma.it\/catechistico\/?p=3464"},"modified":"2023-03-29T10:03:58","modified_gmt":"2023-03-29T08:03:58","slug":"il-kerigma-in-evangelii-gaudium","status":"publish","type":"post","link":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/il-kerigma-in-evangelii-gaudium\/","title":{"rendered":"Il kerigma in Evangelii Gaudium"},"content":{"rendered":"<p>Carissimi,<\/p>\n<p>vi rammentiamo l&#8217;imminente inizio del corso on line di formazione permanente &#8220;<strong>Il kerygma in <em>Evangelii Gaudium<\/em><\/strong>&#8221; (da gioved\u00ec 20 gennaio a gioved\u00ec 3 marzo 2022).<\/p>\n<p>Quest\u2019anno la Diocesi di Roma approfondisce il tema del kerygma, per verificare e migliorare la dimensione di annuncio che \u00e8 necessaria in ogni attivit\u00e0 pastorale. \u00c8 un tema fondamentale per la catechesi. Papa Francesco scrive: \u201cTutta la formazione cristiana \u00e8 prima di tutto l\u2019approfondimento del\u00a0kerygma\u00a0che va facendosi carne sempre pi\u00f9 e sempre meglio, che mai smette di illuminare l\u2019impegno catechistico, e che permette di comprendere adeguatamente il significato di qualunque tema che si sviluppa nella catechesi\u201d (EG 165).<\/p>\n<p>Il corso (completamente gratuito) approfondir\u00e0 diversi aspetti del kerygma, a partire dalla descrizione che il Papa ne d\u00e0 in <em>Evangelii Gaudium<\/em> 164-165.<\/p>\n<p>La proposta \u00e8 un percorso di 7 incontri on line (su piattaforma Cisco Webex, da scaricare sul proprio dispositivo), ogni gioved\u00ec, dalle ore 18.15 alle ore 20.00. Di seguito, le date degli incontri:<\/p>\n<ul>\n<li>20, 27 gennaio; 3, 10, 17, 24 febbraio; 3 marzo.<\/li>\n<\/ul>\n<p>Per essere iscritti nell&#8217;elenco dei partecipanti \u00e8 necessario segnalare la propria adesione inviando una mail all&#8217;indirizzo di posta elettronica del Ns. Ufficio, specificando nome, cognome, telefono, email (a cui poi ricevere le credenziali, che verranno inviate il giorno prima di ogni incontro) e parrocchia di appartenenza.<\/p>\n<p>A presto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Catechistico del Vicariato di Roma<\/p>\n<p>Piazza San Giovanni in Laterano, 6 &#8211; 00184 Roma<\/p>\n<p>e-mail:\u00a0ufficiocatechistico@diocesidiroma.it<\/p>\n<p>Fb Ufficio Catechistico Roma<\/p>\n","protected":false},"excerpt":{"rendered":"Carissimi, vi rammentiamo l&#8217;imminente inizio del corso on line di formazione permanente &#8220;Il kerygma in Evangelii Gaudium&#8221; (da gioved\u00ec 20 gennaio a gioved\u00ec 3 marzo 2022). Quest\u2019anno la Diocesi di Roma approfondisce il tema del kerygma, per verificare e migliorare la dimensione di annuncio che \u00e8 necessaria in ogni attivit\u00e0 pastorale. \u00c8 un tema fondamentale [&hellip;]","protected":false},"author":2,"featured_media":2822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32,13,4],"tags":[],"class_list":["post-3464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formazione-catechisti","category-in_evidenza","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/comments?post=3464"}],"version-history":[{"count":4,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3464\/revisions"}],"predecessor-version":[{"id":3468,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/posts\/3464\/revisions\/3468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/media\/2822"}],"wp:attachment":[{"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/media?parent=3464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/categories?post=3464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/catechistico\/index.php\/wp-json\/wp\/v2\/tags?post=3464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}