{"id":2206,"date":"2021-01-18T09:38:51","date_gmt":"2021-01-18T08:38:51","guid":{"rendered":"https:\/\/www.diocesidiroma.it\/utsroma\/\/?p=2206"},"modified":"2021-01-18T11:32:14","modified_gmt":"2021-01-18T10:32:14","slug":"finanziamenti","status":"publish","type":"post","link":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/finanziamenti\/","title":{"rendered":"Finanziamenti agli oratori, domanda entro il 28 febbraio"},"content":{"rendered":"<p><strong>C\u2019\u00e8 tempo fino al 28 febbraio 2021<\/strong> per presentare la domanda di accesso ai<strong>\u00a0fondi di finanziamento stanziati dalla Regione Lazio<\/strong> per i progetti relativi alle attivit\u00e0 per l\u2019oratorio e a interventi a favore dell\u2019infanzia. Tale contributo \u00e8 a fondo perduto ed \u00e8 previsto dalla <strong>Legge regionale n. 13 del 13 giugno 2001<\/strong>, che \u00abconferisce pieno riconoscimento agli istituti denominati &#8220;Oratori&#8221; che svolgono attivit\u00e0 di educazione e formazione rivolte ad adolescenti e giovani [&#8230;] finalizzate a favorire lo sviluppo, la realizzazione individuale e la socializzazione dei minori, degli adolescenti e dei giovani di qualsiasi nazionalit\u00e0 residenti nel territorio regionale\u00bb. Pi\u00f9 in particolare tale Legge mira a supportare economicamente le attivit\u00e0 volte \u00aba promuovere la realizzazione di programmi, azioni e interventi, finalizzati alla diffusione dello sport e della solidariet\u00e0, alla promozione sociale e di iniziative culturali del tempo libero e al contrasto della emarginazione sociale e della discriminazione razziale, del disagio e della devianza minorile\u00bb.<\/p>\n<p><strong>Per aiutare le parrocchie\u00a0e gli istituti interessati<\/strong>, \u00e8 attivo nella<b> libreria \u201cSinite Parvulos\u201d del Centro oratori romani<\/b>, presso il <strong>Palazzo del Vicariato,<\/strong> uno sportello diocesano di consulenza per la verifica e la presentazione dei progetti e per la formulazione della successiva rendicontazione. Il servizio \u00e8\u00a0aperto ogni luned\u00ec dalle ore 9 alle ore 13. Per facilitare l\u2019accesso ed evitare assembramenti, in osservanza delle misure di sicurezza sanitaria vigenti, \u00e8 possibile prenotare un appuntamento inviando una mail all\u2019indirizzo bandi@centrooratoriromani.org.<\/p>\n<p><strong>I soggetti destinatari dei finanziamenti sono<\/strong> parrocchie, istituti cattolici e altri enti di culto riconosciuti dallo Stato che abbiano sottoscritto gli appositi protocolli d&#8217;intesa previsti dall&#8217;art. 2 della Legge regionale 13 giugno 2001, n. 13, e che svolgano la loro attivit\u00e0 in ambito regionale. I progetti potranno prevedere interventi per le seguenti attivit\u00e0: 1. Attivit\u00e0 di oratorio o similari finalizzate alla promozione, all&#8217;accompagnamento ed al supporto della crescita armonica dei minori, degli adolescenti e dei giovani entro il limite massimo di \u20ac 20.000,00 (art. 3, comma 1); 2. Interventi strutturali finalizzati al potenziamento dell&#8217;offerta di servizi per l&#8217;infanzia a sostegno delle famiglie entro il limite massimo di \u20ac 30.000,00 (art. 2, comma 1 bis); 3. Interventi urgenti per situazioni che impediscono lo svolgersi delle attivit\u00e0 di oratorio, nella misura del 4% dello stanziamento iscritto nell&#8217;apposito capitolo di bilancio (art. 3, comma 2 bis).<\/p>\n<p><strong>Una commissione, istituita con Decreto del Presidente della Giunta regionale<\/strong>, valuter\u00e0 i progetti e conceder\u00e0 i finanziamenti per la loro realizzazione nei limiti dello stanziamento iscritto nel capitolo di bilancio e sulla base di una graduatoria formulata secondo specifici criteri (D.G.R. 13 dicembre 2005, n. 1123 e D.G.R. 2 febbraio 2006, n. 243).<\/p>\n<p>18 gennaio 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019\u00e8 tempo fino al 28 febbraio 2021 per presentare la domanda di accesso ai\u00a0fondi di finanziamento stanziati dalla Regione Lazio per i progetti relativi alle attivit\u00e0 per l\u2019oratorio e a interventi a favore dell\u2019infanzia. Tale contributo \u00e8 a fondo perduto ed \u00e8 previsto dalla Legge regionale n. 13 del 13 giugno 2001, che \u00abconferisce pieno [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[58,64,59,88,29],"class_list":["post-2206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-famiglia","tag-giovani","tag-parrocchie","tag-regione","tag-sport"],"_links":{"self":[{"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":3,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"predecessor-version":[{"id":2210,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/posts\/2206\/revisions\/2210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/media\/2207"}],"wp:attachment":[{"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesidiroma.it\/utsroma\/index.php\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}